{"id":5603,"date":"2026-08-26T19:48:50","date_gmt":"2026-08-26T17:48:50","guid":{"rendered":"https:\/\/elpalaciodelamagia.com\/?post_type=product&#038;p=5603"},"modified":"2026-08-27T10:17:07","modified_gmt":"2026-08-27T08:17:07","slug":"postales-del-palacio-de-la-magia","status":"publish","type":"product","link":"https:\/\/elpalaciodelamagia.com\/en\/product\/postales-del-palacio-de-la-magia\/","title":{"rendered":"Postales del Palacio de la Magia"},"content":{"rendered":"<p>Ll\u00e9vate un peque\u00f1o recuerdo de El Palacio de la Magia de Barcelona. Postales ilustradas con algunos de los personajes y momentos del universo del Palacio.<br \/>\nElige tu favorita, escr\u00edbele unas palabras a alguien especial\u2026 y m\u00e1ndale un poquito de magia. \u2728<br \/>\nDise\u00f1os disponibles<br \/>\nEl Mago del Palacio<br \/>\nLulu &#038; Baby Lulu<br \/>\nBoris &#038; Baby Lisa<br \/>\nEn el reverso encontrar\u00e1s espacio para escribir tu mensaje, direcci\u00f3n y sello, junto al lema \u201cCree en tu Magia\u201d.<\/p>","protected":false},"excerpt":{"rendered":"<p>Una postal puede viajar mucho m\u00e1s lejos que un truco de magia.<br \/>\nLas Postales del Palacio de la Magia est\u00e1n inspiradas en nuestro peque\u00f1o teatro de Barcelona y en sus personajes. Puedes guardarlas como recuerdo, coleccionarlas o envi\u00e1rselas a alguien que necesite un poquito de magia.<\/p>","protected":false},"featured_media":5606,"template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[35],"product_tag":[261,259,260],"class_list":["post-5603","product","type-product","status-publish","has-post-thumbnail","product_cat-accessories","product_tag-fotos","product_tag-postales","product_tag-recuerdos","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-tabs-layout-horizontal","ast-qv-on-image","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Postales del Palacio de la Magia - El Palacio De La Magia<\/title>\n<meta name=\"description\" content=\"Postales ilustradas de El Palacio de la Magia de Barcelona. Elige entre El Mago, Lulu &amp; Baby Lulu y Boris &amp; Baby Lisa. Cree en tu Magia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elpalaciodelamagia.com\/en\/product\/postales-del-palacio-de-la-magia\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Postales del Palacio de la Magia - El Palacio De La Magia\" \/>\n<meta property=\"og:description\" content=\"Postales ilustradas de El Palacio de la Magia de Barcelona. Elige entre El Mago, Lulu &amp; Baby Lulu y Boris &amp; Baby Lisa. Cree en tu Magia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elpalaciodelamagia.com\/en\/product\/postales-del-palacio-de-la-magia\/\" \/>\n<meta property=\"og:site_name\" content=\"El Palacio De La Magia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-27T08:17:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"816\" \/>\n\t<meta property=\"og:image:height\" content=\"1456\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/producto\\\/postales-del-palacio-de-la-magia\\\/\",\"url\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/producto\\\/postales-del-palacio-de-la-magia\\\/\",\"name\":\"Postales del Palacio de la Magia - El Palacio De La Magia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/producto\\\/postales-del-palacio-de-la-magia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/producto\\\/postales-del-palacio-de-la-magia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia.jpg\",\"datePublished\":\"2026-08-26T17:48:50+00:00\",\"dateModified\":\"2026-08-27T08:17:07+00:00\",\"description\":\"Postales ilustradas de El Palacio de la Magia de Barcelona. Elige entre El Mago, Lulu & Baby Lulu y Boris & Baby Lisa. Cree en tu Magia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/producto\\\/postales-del-palacio-de-la-magia\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elpalaciodelamagia.com\\\/producto\\\/postales-del-palacio-de-la-magia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/producto\\\/postales-del-palacio-de-la-magia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia.jpg\",\"contentUrl\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia.jpg\",\"width\":816,\"height\":1456},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/producto\\\/postales-del-palacio-de-la-magia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda de Magia\",\"item\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/en\\\/tienda-de-magia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Postales del Palacio de la Magia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/#website\",\"url\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/\",\"name\":\"El Palacio De La Magia\",\"description\":\"Shows de magia familiar en Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/#organization\",\"name\":\"El Palacio De La Magia\",\"url\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Logo_2023_Letras-Blancas-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Logo_2023_Letras-Blancas-sin-fondo.png\",\"width\":560,\"height\":255,\"caption\":\"El Palacio De La Magia\"},\"image\":{\"@id\":\"https:\\\/\\\/elpalaciodelamagia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Postales del Palacio de la Magia - El Palacio De La Magia","description":"Postales ilustradas de El Palacio de la Magia de Barcelona. Elige entre El Mago, Lulu & Baby Lulu y Boris & Baby Lisa. Cree en tu Magia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elpalaciodelamagia.com\/en\/product\/postales-del-palacio-de-la-magia\/","og_locale":"en_GB","og_type":"article","og_title":"Postales del Palacio de la Magia - El Palacio De La Magia","og_description":"Postales ilustradas de El Palacio de la Magia de Barcelona. Elige entre El Mago, Lulu & Baby Lulu y Boris & Baby Lisa. Cree en tu Magia.","og_url":"https:\/\/elpalaciodelamagia.com\/en\/product\/postales-del-palacio-de-la-magia\/","og_site_name":"El Palacio De La Magia","article_modified_time":"2026-08-27T08:17:07+00:00","og_image":[{"width":816,"height":1456,"url":"https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elpalaciodelamagia.com\/producto\/postales-del-palacio-de-la-magia\/","url":"https:\/\/elpalaciodelamagia.com\/producto\/postales-del-palacio-de-la-magia\/","name":"Postales del Palacio de la Magia - El Palacio De La Magia","isPartOf":{"@id":"https:\/\/elpalaciodelamagia.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elpalaciodelamagia.com\/producto\/postales-del-palacio-de-la-magia\/#primaryimage"},"image":{"@id":"https:\/\/elpalaciodelamagia.com\/producto\/postales-del-palacio-de-la-magia\/#primaryimage"},"thumbnailUrl":"https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia.jpg","datePublished":"2026-08-26T17:48:50+00:00","dateModified":"2026-08-27T08:17:07+00:00","description":"Postales ilustradas de El Palacio de la Magia de Barcelona. Elige entre El Mago, Lulu & Baby Lulu y Boris & Baby Lisa. Cree en tu Magia.","breadcrumb":{"@id":"https:\/\/elpalaciodelamagia.com\/producto\/postales-del-palacio-de-la-magia\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elpalaciodelamagia.com\/producto\/postales-del-palacio-de-la-magia\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/elpalaciodelamagia.com\/producto\/postales-del-palacio-de-la-magia\/#primaryimage","url":"https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia.jpg","contentUrl":"https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia.jpg","width":816,"height":1456},{"@type":"BreadcrumbList","@id":"https:\/\/elpalaciodelamagia.com\/producto\/postales-del-palacio-de-la-magia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elpalaciodelamagia.com\/"},{"@type":"ListItem","position":2,"name":"Tienda de Magia","item":"https:\/\/elpalaciodelamagia.com\/en\/tienda-de-magia\/"},{"@type":"ListItem","position":3,"name":"Postales del Palacio de la Magia"}]},{"@type":"WebSite","@id":"https:\/\/elpalaciodelamagia.com\/#website","url":"https:\/\/elpalaciodelamagia.com\/","name":"The Palace Of The Magic","description":"Shows de magia familiar en Barcelona","publisher":{"@id":"https:\/\/elpalaciodelamagia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elpalaciodelamagia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/elpalaciodelamagia.com\/#organization","name":"The Palace Of The Magic","url":"https:\/\/elpalaciodelamagia.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/elpalaciodelamagia.com\/#\/schema\/logo\/image\/","url":"https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2025\/08\/Logo_2023_Letras-Blancas-sin-fondo.png","contentUrl":"https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2025\/08\/Logo_2023_Letras-Blancas-sin-fondo.png","width":560,"height":255,"caption":"El Palacio De La Magia"},"image":{"@id":"https:\/\/elpalaciodelamagia.com\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia.jpg",816,1456,false],"thumbnail":["https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia-150x150.jpg",150,150,true],"medium":["https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia-168x300.jpg",168,300,true],"medium_large":["https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia-768x1370.jpg",768,1370,true],"large":["https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia-574x1024.jpg",574,1024,true],"1536x1536":["https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia.jpg",816,1456,false],"2048x2048":["https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia.jpg",816,1456,false],"trp-custom-language-flag":["https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia-7x12.jpg",7,12,true],"woocommerce_thumbnail":["https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia-600x1071.jpg",600,1071,true],"woocommerce_gallery_thumbnail":["https:\/\/elpalaciodelamagia.com\/wp-content\/uploads\/2026\/08\/Postal-Lulu-y-Baby-Lulu-de-El-Palacio-de-la-Magia-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"Maximiliano Stia","author_link":"https:\/\/elpalaciodelamagia.com\/en\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Una postal puede viajar mucho m\u00e1s lejos que un truco de magia. Las Postales del Palacio de la Magia est\u00e1n inspiradas en nuestro peque\u00f1o teatro de Barcelona y en sus personajes. Puedes guardarlas como recuerdo, coleccionarlas o envi\u00e1rselas a alguien que necesite un poquito de magia.","_links":{"self":[{"href":"https:\/\/elpalaciodelamagia.com\/en\/wp-json\/wp\/v2\/product\/5603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elpalaciodelamagia.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/elpalaciodelamagia.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elpalaciodelamagia.com\/en\/wp-json\/wp\/v2\/media\/5606"}],"wp:attachment":[{"href":"https:\/\/elpalaciodelamagia.com\/en\/wp-json\/wp\/v2\/media?parent=5603"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/elpalaciodelamagia.com\/en\/wp-json\/wp\/v2\/product_brand?post=5603"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/elpalaciodelamagia.com\/en\/wp-json\/wp\/v2\/product_cat?post=5603"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/elpalaciodelamagia.com\/en\/wp-json\/wp\/v2\/product_tag?post=5603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}